{"id":3300,"date":"2018-07-17T23:48:59","date_gmt":"2018-07-17T21:48:59","guid":{"rendered":"http:\/\/www.lavalledimenticata.it\/?p=3300"},"modified":"2018-07-17T23:48:59","modified_gmt":"2018-07-17T21:48:59","slug":"lavanda-finishing-touch","status":"publish","type":"post","link":"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/","title":{"rendered":"lavanda finishing-touch"},"content":{"rendered":"<div id=\"attachment_3296\" style=\"width: 1210px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3296\" class=\"size-full wp-image-3296\" src=\"http:\/\/www.lavalledimenticata.it\/wp-content\/uploads\/2018\/07\/IMG_20170703_235407.jpg\" alt=\"dig\" width=\"1200\" height=\"900\" srcset=\"https:\/\/www.lavalledimenticata.it\/wp-content\/uploads\/2018\/07\/IMG_20170703_235407.jpg 1200w, https:\/\/www.lavalledimenticata.it\/wp-content\/uploads\/2018\/07\/IMG_20170703_235407-300x225.jpg 300w, https:\/\/www.lavalledimenticata.it\/wp-content\/uploads\/2018\/07\/IMG_20170703_235407-1024x768.jpg 1024w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><p id=\"caption-attachment-3296\" class=\"wp-caption-text\">dig<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":3296,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-3300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entreprise-agricole"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>lavanda finishing-touch - Agriturismo La Valle Dimenticata<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"lavanda finishing-touch - Agriturismo La Valle Dimenticata\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/\" \/>\n<meta property=\"og:site_name\" content=\"Agriturismo La Valle Dimenticata\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-17T21:48:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lavalledimenticata.it\/wp-content\/uploads\/2018\/07\/IMG_20170703_235407.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/\",\"url\":\"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/\",\"name\":\"lavanda finishing-touch - Agriturismo La Valle Dimenticata\",\"isPartOf\":{\"@id\":\"https:\/\/www.lavalledimenticata.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lavalledimenticata.it\/wp-content\/uploads\/2018\/07\/IMG_20170703_235407.jpg\",\"datePublished\":\"2018-07-17T21:48:59+00:00\",\"dateModified\":\"2018-07-17T21:48:59+00:00\",\"author\":{\"@id\":\"https:\/\/www.lavalledimenticata.it\/#\/schema\/person\/6cc7e80e37014bc20eaf9635db3584fa\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/#primaryimage\",\"url\":\"https:\/\/www.lavalledimenticata.it\/wp-content\/uploads\/2018\/07\/IMG_20170703_235407.jpg\",\"contentUrl\":\"https:\/\/www.lavalledimenticata.it\/wp-content\/uploads\/2018\/07\/IMG_20170703_235407.jpg\",\"width\":1200,\"height\":900,\"caption\":\"dig\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.lavalledimenticata.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"lavanda finishing-touch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lavalledimenticata.it\/#website\",\"url\":\"https:\/\/www.lavalledimenticata.it\/\",\"name\":\"Agriturismo La Valle Dimenticata\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lavalledimenticata.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lavalledimenticata.it\/#\/schema\/person\/6cc7e80e37014bc20eaf9635db3584fa\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lavalledimenticata.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0c8c56467aaf5d54cf3f68fd5bc67291?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0c8c56467aaf5d54cf3f68fd5bc67291?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/www.lavalledimenticata.it\/fr\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"lavanda finishing-touch - Agriturismo La Valle Dimenticata","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/","og_locale":"fr_FR","og_type":"article","og_title":"lavanda finishing-touch - Agriturismo La Valle Dimenticata","og_url":"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/","og_site_name":"Agriturismo La Valle Dimenticata","article_published_time":"2018-07-17T21:48:59+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/www.lavalledimenticata.it\/wp-content\/uploads\/2018\/07\/IMG_20170703_235407.jpg","type":"image\/jpeg"}],"author":"admin","twitter_misc":{"\u00c9crit par":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/","url":"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/","name":"lavanda finishing-touch - Agriturismo La Valle Dimenticata","isPartOf":{"@id":"https:\/\/www.lavalledimenticata.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/#primaryimage"},"image":{"@id":"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lavalledimenticata.it\/wp-content\/uploads\/2018\/07\/IMG_20170703_235407.jpg","datePublished":"2018-07-17T21:48:59+00:00","dateModified":"2018-07-17T21:48:59+00:00","author":{"@id":"https:\/\/www.lavalledimenticata.it\/#\/schema\/person\/6cc7e80e37014bc20eaf9635db3584fa"},"breadcrumb":{"@id":"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/#primaryimage","url":"https:\/\/www.lavalledimenticata.it\/wp-content\/uploads\/2018\/07\/IMG_20170703_235407.jpg","contentUrl":"https:\/\/www.lavalledimenticata.it\/wp-content\/uploads\/2018\/07\/IMG_20170703_235407.jpg","width":1200,"height":900,"caption":"dig"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lavalledimenticata.it\/fr\/lavanda-finishing-touch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lavalledimenticata.it\/"},{"@type":"ListItem","position":2,"name":"lavanda finishing-touch"}]},{"@type":"WebSite","@id":"https:\/\/www.lavalledimenticata.it\/#website","url":"https:\/\/www.lavalledimenticata.it\/","name":"Agriturismo La Valle Dimenticata","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lavalledimenticata.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.lavalledimenticata.it\/#\/schema\/person\/6cc7e80e37014bc20eaf9635db3584fa","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lavalledimenticata.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0c8c56467aaf5d54cf3f68fd5bc67291?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c8c56467aaf5d54cf3f68fd5bc67291?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.lavalledimenticata.it\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lavalledimenticata.it\/fr\/wp-json\/wp\/v2\/posts\/3300"}],"collection":[{"href":"https:\/\/www.lavalledimenticata.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lavalledimenticata.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lavalledimenticata.it\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lavalledimenticata.it\/fr\/wp-json\/wp\/v2\/comments?post=3300"}],"version-history":[{"count":1,"href":"https:\/\/www.lavalledimenticata.it\/fr\/wp-json\/wp\/v2\/posts\/3300\/revisions"}],"predecessor-version":[{"id":3301,"href":"https:\/\/www.lavalledimenticata.it\/fr\/wp-json\/wp\/v2\/posts\/3300\/revisions\/3301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lavalledimenticata.it\/fr\/wp-json\/wp\/v2\/media\/3296"}],"wp:attachment":[{"href":"https:\/\/www.lavalledimenticata.it\/fr\/wp-json\/wp\/v2\/media?parent=3300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lavalledimenticata.it\/fr\/wp-json\/wp\/v2\/categories?post=3300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lavalledimenticata.it\/fr\/wp-json\/wp\/v2\/tags?post=3300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}